{"id":2151,"date":"2019-11-18T12:15:20","date_gmt":"2019-11-18T10:15:20","guid":{"rendered":"https:\/\/cpr.afundacion.org\/inicio\/?p=2151"},"modified":"2019-11-18T12:15:20","modified_gmt":"2019-11-18T10:15:20","slug":"visita-a-abanca-innova","status":"publish","type":"post","link":"https:\/\/cpr.afundacion.org\/inicio\/visita-a-abanca-innova\/","title":{"rendered":"Visita a ABANCA Innova"},"content":{"rendered":"<p>El pasado viernes, 15 de noviembre, los alumnos del 2.\u00ba curso del Ciclo Superior de Desarrollo de Aplicaciones Multiplataforma, acompa\u00f1ados por la Directora del centro, Cristina S\u00e1nchez, y los profesores de Inform\u00e1tica, M.\u00aa Jos\u00e9 Blanco, Emilio Pintos y Francisco Ouvi\u00f1a, realizaron una visita guiada al centro ABANCA Innova, situado en el Pol\u00edgono de Pocomaco.<\/p>\n<p>ABANCA Innova es un programa de aceleraci\u00f3n de innovaci\u00f3n abierto de la entidad financiera. Su objetivo es convertirse en el referente del noroeste peninsular e impulsar la iniciativa emprendedora.<\/p>\n<p>Se apoya en su programa de intraemprendimiento, actualmente en su segunda edici\u00f3n, el observatorio tecnol\u00f3gico, sus instalaciones de Vivero y Coworking, donde impulsan las sinergias entre unas empresas y otras en un entorno colaborativo y; por \u00faltimo, mediante su programa de aceleraci\u00f3n.<\/p>\n<p>Durante la visita, profesores y alumnos participaron en un taller creativo, donde pudieron desarrollar y poner en pr\u00e1ctica sus expectativas emprendedoras.<\/p>\n<p><a href=\"https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-9.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2158\" src=\"https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-9.jpeg\" alt=\"\" width=\"2048\" height=\"1536\" srcset=\"https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-9.jpeg 2048w, https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-9-300x225.jpeg 300w, https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-9-768x576.jpeg 768w, https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-9-1024x768.jpeg 1024w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-5.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2157\" src=\"https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-5.jpeg\" alt=\"\" width=\"2048\" height=\"1536\" srcset=\"https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-5.jpeg 2048w, https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-5-300x225.jpeg 300w, https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-5-768x576.jpeg 768w, https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-5-1024x768.jpeg 1024w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-2.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2156\" src=\"https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-2.jpeg\" alt=\"\" width=\"2048\" height=\"1536\" srcset=\"https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-2.jpeg 2048w, https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-2-300x225.jpeg 300w, https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-2-768x576.jpeg 768w, https:\/\/cpr.afundacion.org\/inicio\/wp-content\/uploads\/2019\/11\/ABANCA-INNOVA-2-1024x768.jpeg 1024w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado viernes, 15 de noviembre, los alumnos del 2.\u00ba curso del Ciclo Superior de Desarrollo de Aplicaciones Multiplataforma, acompa\u00f1ados por la Directora del centro, Cristina S\u00e1nchez, y los profesores de Inform\u00e1tica, M.\u00aa Jos\u00e9 Blanco, Emilio Pintos y Francisco Ouvi\u00f1a, realizaron una visita guiada al centro ABANCA Innova, situado en el Pol\u00edgono de Pocomaco. ABANCA [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2155,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-2151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-visitas"],"_links":{"self":[{"href":"https:\/\/cpr.afundacion.org\/inicio\/wp-json\/wp\/v2\/posts\/2151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpr.afundacion.org\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpr.afundacion.org\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpr.afundacion.org\/inicio\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/cpr.afundacion.org\/inicio\/wp-json\/wp\/v2\/comments?post=2151"}],"version-history":[{"count":2,"href":"https:\/\/cpr.afundacion.org\/inicio\/wp-json\/wp\/v2\/posts\/2151\/revisions"}],"predecessor-version":[{"id":2159,"href":"https:\/\/cpr.afundacion.org\/inicio\/wp-json\/wp\/v2\/posts\/2151\/revisions\/2159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpr.afundacion.org\/inicio\/wp-json\/wp\/v2\/media\/2155"}],"wp:attachment":[{"href":"https:\/\/cpr.afundacion.org\/inicio\/wp-json\/wp\/v2\/media?parent=2151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpr.afundacion.org\/inicio\/wp-json\/wp\/v2\/categories?post=2151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpr.afundacion.org\/inicio\/wp-json\/wp\/v2\/tags?post=2151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}